{"id":104636,"date":"2021-04-16T14:21:00","date_gmt":"2021-04-16T11:21:00","guid":{"rendered":"https:\/\/howto.mediadoma.com\/?p=104636"},"modified":"2025-03-15T01:13:07","modified_gmt":"2025-03-14T22:13:07","slug":"como-alterar-a-hora-e-a-data-no-windows-10","status":"publish","type":"post","link":"https:\/\/howto.mediadoma.com\/pt-pt\/como-alterar-a-hora-e-a-data-no-windows-10\/","title":{"rendered":"Como alterar a hora e a data no Windows 10"},"content":{"rendered":"<h2>Como alterar a hora no Windows 10?<\/h2>\n<p>Veja como ajustar rapidamente essas configura\u00e7\u00f5es:<\/p>\n<ul>\n<li>A primeira coisa que voc\u00ea precisa fazer \u00e9 clicar com o bot\u00e3o direito no rel\u00f3gio na barra de tarefas<\/li>\n<li>Na lista de resultados, selecione <strong>Ajustar data \/ hora<\/strong><\/li>\n<\/ul>\n<p><a href=\"https:\/\/howto.mediadoma.com\/wp-content\/uploads\/2021\/03\/post-81895-60510a6a08317.jpg\" data-rel=\"lightbox\" ><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/howto.mediadoma.com\/wp-content\/uploads\/2021\/03\/post-81895-60510a6a08317.jpg\" alt=\"Como alterar a hora e a data no Windows 10\" ><\/a><\/p>\n<ul>\n<li>Voc\u00ea ser\u00e1 direcionado para a guia <strong>Tempo e idioma<\/strong> no aplicativo <strong>Configura\u00e7\u00f5es<\/strong>. (Observa\u00e7\u00e3o: voc\u00ea tamb\u00e9m pode acessar a janela Data e hora no Painel de controle).<\/li>\n<\/ul>\n<p><a href=\"https:\/\/howto.mediadoma.com\/wp-content\/uploads\/2021\/03\/post-81895-60510a6b070e3.png\" data-rel=\"lightbox\" ><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/howto.mediadoma.com\/wp-content\/uploads\/2021\/03\/post-81895-60510a6b070e3.png\" alt=\"Como alterar a hora e a data no Windows 10\" ><\/a><\/p>\n<ul>\n<li>Clique no <strong>bot\u00e3o Alterar<\/strong> em Alterar data e hora e use o menu suspenso para selecionar os valores desejados.<\/li>\n<li>Se preferir, voc\u00ea pode escolher <strong>Definir a hora automaticamente<\/strong> (o que sincronizar\u00e1 automaticamente o rel\u00f3gio do seu PC com o rel\u00f3gio da Internet).<\/li>\n<\/ul>\n<p><a href=\"https:\/\/howto.mediadoma.com\/wp-content\/uploads\/2021\/03\/post-81895-60510a6c4c4bf.jpg\" data-rel=\"lightbox\" ><img decoding=\"async\" class=\"SDStudio-light-box-enable SDStudio-editor-tools-md-imp\" src=\"https:\/\/howto.mediadoma.com\/wp-content\/uploads\/2021\/03\/post-81895-60510a6c4c4bf.jpg\" alt=\"Como alterar a hora e a data no Windows 10\" ><\/a><\/p>\n<ul>\n<li>\n<p>A seguir, voc\u00ea ver\u00e1 a se\u00e7\u00e3o <strong>Configura\u00e7\u00f5es relacionadas<\/strong>. Clique no link <strong>Data, hora e formata\u00e7\u00e3o regional<\/strong> para modificar o formato de acordo com suas necessidades (voc\u00ea pode definir o primeiro dia da semana, data abreviada, data longa, hora curta e longa e assim por diante).<\/p>\n<\/li>\n<li>\n<ul>\n<li>*<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>\u00c9 isso! Como voc\u00ea pode ver, essa op\u00e7\u00e3o n\u00e3o mudou muito e, se voc\u00ea j\u00e1 usou esse recurso no Windows 8, deve se familiarizar com ele.<\/p>\n<p>Talvez a maior mudan\u00e7a seja que voc\u00ea n\u00e3o pode clicar no rel\u00f3gio na barra de tarefas e alterar a hora e a data rapidamente como antes; em vez disso, voc\u00ea precisa contar com a se\u00e7\u00e3o Data e hora no aplicativo Configura\u00e7\u00f5es.<\/p>\n<p>Deixe-nos saber se esta postagem foi \u00fatil atrav\u00e9s da se\u00e7\u00e3o de coment\u00e1rios abaixo.<\/p>\n<p><strong>Nota do editor:<\/strong> este post foi publicado originalmente em dezembro de 2015 e desde ent\u00e3o foi reformulado e atualizado em maio de 2020 para atualiza\u00e7\u00e3o, precis\u00e3o e abrang\u00eancia.<\/p>\n<p><div id=\"PostUnique_PostSource\" style=\"padding-top: 50px\">Fonte de grava\u00e7\u00e3o:  <a target=\"_blank\" rel=\"noopener nofollow\" href=\"\/\/windowsreport.com\" class=\"external external_icon\">windowsreport.com<\/a><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea n\u00e3o precisa de nenhuma habilidade especial para alterar a data e a hora no Windows 10. Essa tarefa \u00e9 t\u00e3o f\u00e1cil quanto brisa, basta seguir estas etapas r\u00e1pidas.<\/p>\n","protected":false},"author":1,"featured_media":136525,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_wp_rev_ctl_limit":""},"categories":[991],"tags":[3061],"class_list":["post-104636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-skype-para-negocios","tag-affiai-pt-pt"],"_links":{"self":[{"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/posts\/104636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=104636"}],"version-history":[{"count":1,"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/posts\/104636\/revisions"}],"predecessor-version":[{"id":315841,"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/posts\/104636\/revisions\/315841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/media\/136525"}],"wp:attachment":[{"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=104636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=104636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/howto.mediadoma.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=104636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}